{"id":8834,"date":"2025-05-23T19:10:11","date_gmt":"2025-05-23T17:10:11","guid":{"rendered":"https:\/\/lantestina.lifty.agency\/why-lantestina\/"},"modified":"2025-06-12T08:54:24","modified_gmt":"2025-06-12T06:54:24","slug":"wieso-lantestina","status":"publish","type":"page","link":"https:\/\/www.lantestina.com\/de\/wieso-lantestina\/","title":{"rendered":"Wieso Lantestina"},"content":{"rendered":"<style>.kb-row-layout-id8834_d74c68-e1 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id8834_d74c68-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id8834_d74c68-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:160px;padding-bottom:160px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_d74c68-e1{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_d74c68-e1{background-image:url('https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-flower-16.png');background-size:contain;background-position:25% 3%;background-attachment:scroll;background-repeat:repeat;}.kb-row-layout-id8834_d74c68-e1 > .kt-row-layout-overlay{opacity:0.77;background-color:var(--global-palette8, #F7FAFC);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id8834_d74c68-e1 > .kt-row-column-wrap{padding-top:200px;padding-bottom:200px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id8834_d74c68-e1{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_d74c68-e1 > .kt-row-column-wrap{padding-top:60px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:60px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_d74c68-e1{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id8834_d74c68-e1{background-image:url('https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina_odabrano-idejno-rjesenje_14.7.-11-1-e1747409874191.png')!important;background-size:auto;background-position:28.000000000000004% 33%;background-attachment:fixed;background-repeat:repeat;}}<\/style><div style=\"background-image: url(https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-flower-16.png)\" class=\"kb-row-layout-wrap kb-row-layout-id8834_d74c68-e1 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom\">\n<style>.kadence-column8834_da32ce-dc > .kt-inside-inner-col{display:flex;}.kadence-column8834_da32ce-dc > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column8834_da32ce-dc > .kt-inside-inner-col,.kadence-column8834_da32ce-dc > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column8834_da32ce-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_da32ce-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_da32ce-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_da32ce-dc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_da32ce-dc > .kt-inside-inner-col{background-color:rgba(236, 230, 220, 0.93);}.kadence-column8834_da32ce-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_da32ce-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_da32ce-dc > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_da32ce-dc{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_da32ce-dc, .kt-inside-inner-col > .kadence-column8834_da32ce-dc:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column8834_da32ce-dc > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column8834_da32ce-dc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_da32ce-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_da32ce-dc, .kt-inside-inner-col > .kadence-column8834_da32ce-dc:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_da32ce-dc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56, .wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56[data-kb-block=\"kb-adv-heading8834_967876-56\"]{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56[data-kb-block=\"kb-adv-heading8834_967876-56\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56[data-kb-block=\"kb-adv-heading8834_967876-56\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56, .wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56[data-kb-block=\"kb-adv-heading8834_967876-56\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56, .wp-block-kadence-advancedheading.kt-adv-heading8834_967876-56[data-kb-block=\"kb-adv-heading8834_967876-56\"]{padding-right:0px;padding-left:0px;font-size:25px;}}<\/style>\n<h1 class=\"kt-adv-heading8834_967876-56 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_967876-56\">Wieso Lantestina?<\/h1>\n\n\n<style>.wp-block-kadence-image.kb-image8834_3918d6-f4:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-image8834_3918d6-f4.kb-image-is-ratio-size, .kb-image8834_3918d6-f4 .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image8834_3918d6-f4.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image8834_3918d6-f4 .kb-image-is-ratio-size{align-self:unset;}.kb-image8834_3918d6-f4 figure{max-width:142px;}.kb-image8834_3918d6-f4 .image-is-svg, .kb-image8834_3918d6-f4 .image-is-svg img{width:100%;}.kb-image8834_3918d6-f4:not(.kb-image-is-ratio-size) .kb-img, .kb-image8834_3918d6-f4.kb-image-is-ratio-size{padding-top:0px;padding-bottom:0px;}.kb-image8834_3918d6-f4 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image8834_3918d6-f4:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}}@media all and (max-width: 1024px){.kb-image8834_3918d6-f4.kb-image-is-ratio-size, .kb-image8834_3918d6-f4 .kb-image-is-ratio-size{max-width:100px;width:100%;}}@media all and (max-width: 1024px){.kb-image8834_3918d6-f4 figure{max-width:100px;}}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image8834_3918d6-f4:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image8834_3918d6-f4.kb-image-is-ratio-size, .kb-image8834_3918d6-f4 .kb-image-is-ratio-size{max-width:100px;width:100%;}.kb-image8834_3918d6-f4 figure{max-width:100px;}.kb-image8834_3918d6-f4:not(.kb-image-is-ratio-size) .kb-img, .kb-image8834_3918d6-f4.kb-image-is-ratio-size{padding-top:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image8834_3918d6-f4\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341.png\" alt=\"\" class=\"kb-img wp-image-2041\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341.png 960w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-300x300.png 300w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-150x150.png 150w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-768x768.png 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-380x380.png 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-700x700.png 700w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-100x100.png 100w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3, .wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3[data-kb-block=\"kb-adv-heading8834_e2a791-e3\"]{max-width:229px;margin-right:auto;margin-left:auto;padding-bottom:var(--global-kb-spacing-lg, 3rem);margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;font-family:'DM Sans';text-transform:uppercase;letter-spacing:2px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3[data-kb-block=\"kb-adv-heading8834_e2a791-e3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3[data-kb-block=\"kb-adv-heading8834_e2a791-e3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3, .wp-block-kadence-advancedheading.kt-adv-heading8834_e2a791-e3[data-kb-block=\"kb-adv-heading8834_e2a791-e3\"]{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);margin-top:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<p class=\"kt-adv-heading8834_e2a791-e3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_e2a791-e3\">Naturkosmetik inspiriert von blumen<\/p>\n\n\n<style>.kb-row-layout-id8834_cabb28-7c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_cabb28-7c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_cabb28-7c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_cabb28-7c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_cabb28-7c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_cabb28-7c > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_cabb28-7c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_3b817a-30 > .kt-inside-inner-col,.kadence-column8834_3b817a-30 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_3b817a-30 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_3b817a-30 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_3b817a-30 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_3b817a-30 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_3b817a-30{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_3b817a-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_3b817a-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_3b817a-30\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left wp-block-paragraph\">Lantestina ist eine zertifizierte Linie f\u00fcr<em> nat\u00fcrliche &amp; biologische Kosmetik<\/em>, entstanden aus der \u00dcberzeugung, dass die wertvollsten <em>Wirkstoffe <\/em>aus den <em>Pflanzen <\/em>kommen, die uns <em>umgeben<\/em>. Wir glauben an die <em>Kraft des Lokalen und Wirkstoffreichen<\/em> \u2013 und entwickeln Hautpflegeprodukte, die genau das beweisen.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id8834_ece454-36{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_ece454-36 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_ece454-36{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8834_ece454-36 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}.kb-row-layout-id8834_ece454-36{border-bottom:1px solid var(--global-palette9, #ffffff);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_ece454-36 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_63669e-a4 > .kt-inside-inner-col{display:flex;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col{padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column8834_63669e-a4 > .kt-inside-inner-col,.kadence-column8834_63669e-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_63669e-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_63669e-a4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_63669e-a4{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_63669e-a4 > .kt-inside-inner-col{padding-left:0px;flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_63669e-a4{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_63669e-a4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_63669e-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_63669e-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_63669e-a4 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_42c417-97 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_42c417-97 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_42c417-97 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1920px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_42c417-97{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_42c417-97 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_42c417-97 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_42c417-97 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_42c417-97 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8834_bb325a-73 > .kt-inside-inner-col,.kadence-column8834_bb325a-73 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_bb325a-73 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_bb325a-73 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_bb325a-73 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_bb325a-73 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_bb325a-73{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_bb325a-73 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_bb325a-73 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_bb325a-73 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05, .wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05[data-kb-block=\"kb-adv-heading8834_51a568-05\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;font-family:'DM Sans';text-transform:uppercase;letter-spacing:2px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05[data-kb-block=\"kb-adv-heading8834_51a568-05\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05[data-kb-block=\"kb-adv-heading8834_51a568-05\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05, .wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05[data-kb-block=\"kb-adv-heading8834_51a568-05\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05, .wp-block-kadence-advancedheading.kt-adv-heading8834_51a568-05[data-kb-block=\"kb-adv-heading8834_51a568-05\"]{padding-top:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-sm, 0.9rem);}}<\/style>\n<h3 class=\"kt-adv-heading8834_51a568-05 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_51a568-05\">Was uns besonders macht<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91, .wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91[data-kb-block=\"kb-adv-heading8834_8856a6-91\"]{max-width:506px;padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91[data-kb-block=\"kb-adv-heading8834_8856a6-91\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91[data-kb-block=\"kb-adv-heading8834_8856a6-91\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91, .wp-block-kadence-advancedheading.kt-adv-heading8834_8856a6-91[data-kb-block=\"kb-adv-heading8834_8856a6-91\"]{font-size:24px;}}<\/style>\n<h2 class=\"kt-adv-heading8834_8856a6-91 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_8856a6-91\">Wiesenkr\u00e4uter \u2013 ein vergessenes <em>Juwel <\/em>der Hautpflege<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98, .wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98[data-kb-block=\"kb-adv-heading8834_a76298-98\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98[data-kb-block=\"kb-adv-heading8834_a76298-98\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_a76298-98[data-kb-block=\"kb-adv-heading8834_a76298-98\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_a76298-98 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_a76298-98\">Unsere Naturkosmetik basiert auf kraftvollen Extrakten aus heimischen Wiesenpflanzen wie Frauenmantel, Ehrenpreis, Schafgarbe, Gro\u00dfer Wiesenknopf (<em>Sanguisorba officinalis<\/em>) und Schwarzer Malve \u2013 erg\u00e4nzt durch kaltgepresste, pflanzliche \u00d6le. Obwohl diese <em>Heilpflanzen <\/em>seit Jahrhunderten bekannt sind, finden sie in der modernen Kosmetik <em>kaum <\/em>Beachtung. Genau das m\u00f6chten wir \u00e4ndern. Wir m\u00f6chten ihre hautpflegenden Eigenschaften wieder ins Bewusstsein rufen und ihre Wirkung in moderner <em>Clean Beauty<\/em> verankern.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80, .wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80[data-kb-block=\"kb-adv-heading8834_6d4ef1-80\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80[data-kb-block=\"kb-adv-heading8834_6d4ef1-80\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_6d4ef1-80[data-kb-block=\"kb-adv-heading8834_6d4ef1-80\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_6d4ef1-80 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_6d4ef1-80\">Jeder Inhaltsstoff wird mit gr\u00f6\u00dfter <em>Sorgfalt <\/em>ausgew\u00e4hlt \u2013 f\u00fcr sp\u00fcrbare <em>Wirkung <\/em>und <em>ganzheitliche Hautgesundheit<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neben den ausgew\u00e4hlten botanischen Wirkstoffen setzen wir ausschlie\u00dflich auf nachhaltig gewonnene Rohstoffe \u2013 <em>biologisch zertifiziert<\/em>, <em>schonend verarbeitet <\/em>oder als <em>Nebenprodukt <\/em>anderer Industrien gewonnen \u2013 ein echter Beitrag zur <em>Zero-Waste-Philosophie<\/em> und Nachhaltigkeit.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{display:flex;}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col,.kadence-column8834_3a1740-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_3a1740-a1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_3a1740-a1{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_3a1740-a1{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_3a1740-a1{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_3a1740-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_3a1740-a1 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap{max-width:1707px;overflow:hidden;}.kt-img-overlay8834_be1b28-f7{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap, .kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap{max-width:1707px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:200%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap{max-width:1707px;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:133.33%;}.kt-img-overlay8834_be1b28-f7 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_be1b28-f7 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" class=\"kt-img-overlay wp-image-1464\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--scaled.jpg 1707w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--200x300.jpg 200w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--683x1024.jpg 683w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--768x1152.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--1024x1536.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--1365x2048.jpg 1365w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--380x570.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-main-ingrediant--700x1050.jpg 700w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id8834_eb7f9f-c2{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_eb7f9f-c2{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_eb7f9f-c2 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_eb7f9f-c2{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_eb7f9f-c2 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{display:flex;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col,.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_ba1c5d-d4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_ba1c5d-d4{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_ba1c5d-d4{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_ba1c5d-d4{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_ba1c5d-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_ba1c5d-d4 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap{max-width:1920px;overflow:hidden;}.kt-img-overlay8834_66a77c-da{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap, .kt-img-overlay8834_66a77c-da .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_66a77c-da .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_66a77c-da .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap{max-width:1920px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:200%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_66a77c-da .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap{max-width:1920px;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:133.33%;}.kt-img-overlay8834_66a77c-da .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_66a77c-da aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare.jpg\" alt=\"\" width=\"1920\" height=\"1280\" class=\"kt-img-overlay wp-image-8971\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare.jpg 1920w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-300x200.jpg 300w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-1024x683.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-768x512.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-1536x1024.jpg 1536w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-380x253.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-natural-skincare-700x467.jpg 700w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{display:flex;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col,.kadence-column8834_6ffca6-4f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_6ffca6-4f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_6ffca6-4f{position:relative;}.kadence-column8834_6ffca6-4f, .kt-inside-inner-col > .kadence-column8834_6ffca6-4f:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_6ffca6-4f{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_6ffca6-4f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_6ffca6-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_6ffca6-4f inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_143c0a-0e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_143c0a-0e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_143c0a-0e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:580px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_143c0a-0e{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_143c0a-0e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_143c0a-0e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_143c0a-0e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_143c0a-0e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_960174-55 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_960174-55 > .kt-inside-inner-col,.kadence-column8834_960174-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_960174-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_960174-55 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_960174-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_960174-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_960174-55{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_960174-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_960174-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_960174-55 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66, .wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66[data-kb-block=\"kb-adv-heading8834_86bed4-66\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;font-family:'DM Sans';text-transform:uppercase;letter-spacing:2px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66[data-kb-block=\"kb-adv-heading8834_86bed4-66\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66[data-kb-block=\"kb-adv-heading8834_86bed4-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66, .wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66[data-kb-block=\"kb-adv-heading8834_86bed4-66\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66, .wp-block-kadence-advancedheading.kt-adv-heading8834_86bed4-66[data-kb-block=\"kb-adv-heading8834_86bed4-66\"]{padding-top:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-sm, 0.9rem);}}<\/style>\n<h3 class=\"kt-adv-heading8834_86bed4-66 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_86bed4-66\">NAT\u00dcRLICH &amp; WIRKSAM<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff, .wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff[data-kb-block=\"kb-adv-heading8834_c018ac-ff\"]{max-width:676px;padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff[data-kb-block=\"kb-adv-heading8834_c018ac-ff\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff[data-kb-block=\"kb-adv-heading8834_c018ac-ff\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff, .wp-block-kadence-advancedheading.kt-adv-heading8834_c018ac-ff[data-kb-block=\"kb-adv-heading8834_c018ac-ff\"]{font-size:24px;}}<\/style>\n<h2 class=\"kt-adv-heading8834_c018ac-ff wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_c018ac-ff\">Inhaltsstoffe mit <em>sichtbarem <\/em>Effekt<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8, .wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8[data-kb-block=\"kb-adv-heading8834_90bf44-d8\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8[data-kb-block=\"kb-adv-heading8834_90bf44-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_90bf44-d8[data-kb-block=\"kb-adv-heading8834_90bf44-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_90bf44-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_90bf44-d8\">Unsere Pflegeprodukte sind f\u00fcr <em>alle Hauttypen <\/em>geeignet \u2013 sie wirken nicht nur pflegend, sondern <em>aktivierend<\/em>. Mit <em>hochwirksamen, naturbasierten <\/em>Inhaltsstoffen st\u00e4rken sie die nat\u00fcrlichen <em>Funktionen <\/em>Ihrer Haut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Pflanzenextrakte und <em>kaltgepressten <\/em>\u00d6le werden erg\u00e4nzt durch moderne <em>Wirkstoffe <\/em>aus der Natur: <em>pr\u00e4biotische Komplexe, pflanzliche Hyalurons\u00e4ure und Extrakte des Gro\u00dfen Wiesenknopfs<\/em>. Sie f\u00f6rdern das <em>Gleichgewicht <\/em>der Haut, spenden <em>Feuchtigkeit <\/em>und sorgen f\u00fcr nat\u00fcrliche <em>Ausstrahlung<\/em>.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id8834_7b483f-f3{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_7b483f-f3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_7b483f-f3{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8834_7b483f-f3 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}.kb-row-layout-id8834_7b483f-f3{border-bottom:1px solid var(--global-palette9, #ffffff);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_7b483f-f3 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{display:flex;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col,.kadence-column8834_d1058a-d5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_d1058a-d5{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_d1058a-d5{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_d1058a-d5{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_d1058a-d5{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_d1058a-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_d1058a-d5 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_2c38f4-8e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_2c38f4-8e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_2c38f4-8e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1920px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_2c38f4-8e{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_2c38f4-8e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_2c38f4-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_2c38f4-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_2c38f4-8e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8834_de1e61-ab > .kt-inside-inner-col,.kadence-column8834_de1e61-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_de1e61-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_de1e61-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_de1e61-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_de1e61-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_de1e61-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_de1e61-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_de1e61-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_de1e61-ab inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30, .wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30[data-kb-block=\"kb-adv-heading8834_f058ad-30\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;font-family:'DM Sans';text-transform:uppercase;letter-spacing:2px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30[data-kb-block=\"kb-adv-heading8834_f058ad-30\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30[data-kb-block=\"kb-adv-heading8834_f058ad-30\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30, .wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30[data-kb-block=\"kb-adv-heading8834_f058ad-30\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30, .wp-block-kadence-advancedheading.kt-adv-heading8834_f058ad-30[data-kb-block=\"kb-adv-heading8834_f058ad-30\"]{padding-top:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-sm, 0.9rem);}}<\/style>\n<h3 class=\"kt-adv-heading8834_f058ad-30 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_f058ad-30\">absolute transparenz<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54, .wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54[data-kb-block=\"kb-adv-heading8834_22881a-54\"]{max-width:738px;padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54[data-kb-block=\"kb-adv-heading8834_22881a-54\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54[data-kb-block=\"kb-adv-heading8834_22881a-54\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54, .wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54[data-kb-block=\"kb-adv-heading8834_22881a-54\"]{font-size:24px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54, .wp-block-kadence-advancedheading.kt-adv-heading8834_22881a-54[data-kb-block=\"kb-adv-heading8834_22881a-54\"]{max-width:229px;}}<\/style>\n<h2 class=\"kt-adv-heading8834_22881a-54 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_22881a-54\">Eigene Herstellung in <em>kleinen <\/em>Chargen<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30, .wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30[data-kb-block=\"kb-adv-heading8834_075d68-30\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30[data-kb-block=\"kb-adv-heading8834_075d68-30\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_075d68-30[data-kb-block=\"kb-adv-heading8834_075d68-30\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_075d68-30 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_075d68-30\">Alle Lantestina-Produkte entstehen in unserem eigenen <em>Labor <\/em>\u2013 in sorgf\u00e4ltiger Handarbeit und <em>kleinen <\/em>Mengen. So garantieren wir maximale <em>Frische<\/em>, strenge <em>Qualit\u00e4tskontrollen<\/em> in jedem <em>Produktionsschritt<\/em>.<\/p>\n\n\n\n<p class=\"has-theme-palette-3-color has-text-color has-link-color wp-elements-339f27eb48b44c8a0e9804b6accd8827 wp-block-paragraph\">Unsere <em>Zertifizierung <\/em>nach dem <a href=\"https:\/\/www.lantestina.com\/de\/natrue-zertifizierung\/\" data-type=\"page\" data-id=\"960\">NATRUE <\/a>Standard belegt unsere Werte \u2013 f\u00fcr reine Naturkosmetik, der Sie vertrauen k\u00f6nnen.<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column8834_0028c4-98 > .kt-inside-inner-col{display:flex;}.kadence-column8834_0028c4-98 > .kt-inside-inner-col,.kadence-column8834_0028c4-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_0028c4-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_0028c4-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_0028c4-98{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_0028c4-98 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column8834_0028c4-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_0028c4-98{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_0028c4-98{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_0028c4-98{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_0028c4-98 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_0028c4-98 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap{max-width:1920px;overflow:hidden;}.kt-img-overlay8834_1d912a-cc{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap, .kt-img-overlay8834_1d912a-cc .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_1d912a-cc .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_1d912a-cc .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap{max-width:1920px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:200%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_1d912a-cc .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap{max-width:1920px;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:133.33%;}.kt-img-overlay8834_1d912a-cc .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_1d912a-cc aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos.jpg\" alt=\"\" width=\"1920\" height=\"1281\" class=\"kt-img-overlay wp-image-10156\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos.jpg 1920w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-300x200.jpg 300w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-1024x683.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-768x512.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-1536x1025.jpg 1536w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-380x254.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-Labos-700x467.jpg 700w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_98a3f7-1f > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id8834_98a3f7-1f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id8834_98a3f7-1f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:220px;padding-bottom:220px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_98a3f7-1f{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_98a3f7-1f{background-image:url('https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-flowers-09.png');background-size:contain;background-position:25% 3%;background-attachment:scroll;background-repeat:repeat;}.kb-row-layout-id8834_98a3f7-1f > .kt-row-layout-overlay{opacity:0.77;background-color:var(--global-palette8, #F7FAFC);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id8834_98a3f7-1f > .kt-row-column-wrap{padding-top:200px;padding-bottom:200px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id8834_98a3f7-1f{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_98a3f7-1f > .kt-row-column-wrap{padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_98a3f7-1f{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id8834_98a3f7-1f{background-image:url('https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-flowers-09.png')!important;background-size:auto;background-position:28.000000000000004% 33%;background-attachment:fixed;background-repeat:repeat;}}<\/style><div style=\"background-image: url(https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina-flowers-09.png)\" class=\"kb-row-layout-wrap kb-row-layout-id8834_98a3f7-1f alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"ritual\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom\">\n<style>.kadence-column8834_4d0023-63 > .kt-inside-inner-col{display:flex;}.kadence-column8834_4d0023-63 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.kadence-column8834_4d0023-63 > .kt-inside-inner-col,.kadence-column8834_4d0023-63 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column8834_4d0023-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_4d0023-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_4d0023-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_4d0023-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_4d0023-63 > .kt-inside-inner-col{background-color:rgba(236, 230, 220, 0.93);}.kadence-column8834_4d0023-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_4d0023-63{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_4d0023-63 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_4d0023-63{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_4d0023-63, .kt-inside-inner-col > .kadence-column8834_4d0023-63:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column8834_4d0023-63 > .kt-inside-inner-col{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column8834_4d0023-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_4d0023-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_4d0023-63, .kt-inside-inner-col > .kadence-column8834_4d0023-63:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_4d0023-63 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95, .wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95[data-kb-block=\"kb-adv-heading8834_582e1c-95\"]{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95[data-kb-block=\"kb-adv-heading8834_582e1c-95\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95[data-kb-block=\"kb-adv-heading8834_582e1c-95\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95, .wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95[data-kb-block=\"kb-adv-heading8834_582e1c-95\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95, .wp-block-kadence-advancedheading.kt-adv-heading8834_582e1c-95[data-kb-block=\"kb-adv-heading8834_582e1c-95\"]{padding-right:0px;padding-left:0px;font-size:25px;}}<\/style>\n<h1 class=\"kt-adv-heading8834_582e1c-95 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_582e1c-95\">Das Ritual<\/h1>\n\n\n<style>.wp-block-kadence-image.kb-image8834_cfd07e-8a:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-image8834_cfd07e-8a.kb-image-is-ratio-size, .kb-image8834_cfd07e-8a .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image8834_cfd07e-8a.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image8834_cfd07e-8a .kb-image-is-ratio-size{align-self:unset;}.kb-image8834_cfd07e-8a figure{max-width:142px;}.kb-image8834_cfd07e-8a .image-is-svg, .kb-image8834_cfd07e-8a .image-is-svg img{width:100%;}.kb-image8834_cfd07e-8a:not(.kb-image-is-ratio-size) .kb-img, .kb-image8834_cfd07e-8a.kb-image-is-ratio-size{padding-top:0px;padding-bottom:0px;}.kb-image8834_cfd07e-8a .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image8834_cfd07e-8a:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}}@media all and (max-width: 1024px){.kb-image8834_cfd07e-8a.kb-image-is-ratio-size, .kb-image8834_cfd07e-8a .kb-image-is-ratio-size{max-width:100px;width:100%;}}@media all and (max-width: 1024px){.kb-image8834_cfd07e-8a figure{max-width:100px;}}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image8834_cfd07e-8a:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image8834_cfd07e-8a.kb-image-is-ratio-size, .kb-image8834_cfd07e-8a .kb-image-is-ratio-size{max-width:100px;width:100%;}.kb-image8834_cfd07e-8a figure{max-width:100px;}.kb-image8834_cfd07e-8a:not(.kb-image-is-ratio-size) .kb-img, .kb-image8834_cfd07e-8a.kb-image-is-ratio-size{padding-top:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image8834_cfd07e-8a\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341.png\" alt=\"\" class=\"kb-img wp-image-2041\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341.png 960w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-300x300.png 300w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-150x150.png 150w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-768x768.png 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-380x380.png 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-700x700.png 700w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Lantestina__Znak_A_pozitiv-edited-e1747595628341-100x100.png 100w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e, .wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e[data-kb-block=\"kb-adv-heading8834_df7243-1e\"]{max-width:229px;margin-right:auto;margin-left:auto;padding-bottom:var(--global-kb-spacing-lg, 3rem);margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;font-family:'DM Sans';text-transform:uppercase;letter-spacing:2px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e[data-kb-block=\"kb-adv-heading8834_df7243-1e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e[data-kb-block=\"kb-adv-heading8834_df7243-1e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e, .wp-block-kadence-advancedheading.kt-adv-heading8834_df7243-1e[data-kb-block=\"kb-adv-heading8834_df7243-1e\"]{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);margin-top:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<p class=\"kt-adv-heading8834_df7243-1e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_df7243-1e\">DIE VIER SCHRITTE IHRER HAUTPFLEGEROUTINE<\/p>\n\n\n<style>.kb-row-layout-id8834_7115b1-9f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_7115b1-9f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_7115b1-9f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_7115b1-9f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_7115b1-9f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_7115b1-9f > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_7115b1-9f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_0392d8-1a > .kt-inside-inner-col,.kadence-column8834_0392d8-1a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_0392d8-1a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_0392d8-1a > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_0392d8-1a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_0392d8-1a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_0392d8-1a{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_0392d8-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_0392d8-1a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_0392d8-1a\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left wp-block-paragraph\">Das Lantestina-Ritual beruht auf der Synergie aus vier <em>perfekt <\/em>aufeinander <em>abgestimmten <\/em>Schritten \u2013 jede Phase erf\u00fcllt eine pr\u00e4zise <em>Funktion <\/em>und gemeinsam bilden sie ein <em>ganzheitliches Pflegesystem <\/em>f\u00fcr<em> gesunde, strahlende <\/em>und <em>balancierte<\/em> Haut.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_b07168-1e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_b07168-1e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_b07168-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8834_b07168-1e{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_b07168-1e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_b07168-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_b07168-1e{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_b07168-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:80px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:80px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_b07168-1e{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_b07168-1e alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_c8f027-43 > .kt-inside-inner-col{display:flex;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col,.kadence-column8834_c8f027-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_c8f027-43{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_c8f027-43{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_c8f027-43{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_c8f027-43{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_c8f027-43 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_c8f027-43 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap{max-width:1707px;overflow:hidden;}.kt-img-overlay8834_a27b25-99{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap, .kt-img-overlay8834_a27b25-99 .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a27b25-99 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a27b25-99 .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap{max-width:1707px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_a27b25-99 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap{max-width:1707px;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:150%;}.kt-img-overlay8834_a27b25-99 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_a27b25-99 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" class=\"kt-img-overlay wp-image-8996\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-scaled.jpg 1707w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-200x300.jpg 200w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-683x1024.jpg 683w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-768x1152.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-1024x1536.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-1365x2048.jpg 1365w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-380x570.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Balm-700x1050.jpg 700w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8834_d85ada-63 > .kt-inside-inner-col{display:flex;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col,.kadence-column8834_d85ada-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_d85ada-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_d85ada-63{position:relative;}.kadence-column8834_d85ada-63, .kt-inside-inner-col > .kadence-column8834_d85ada-63:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_d85ada-63{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_d85ada-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_d85ada-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_d85ada-63 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_c9b217-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_c9b217-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_c9b217-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:580px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_c9b217-11{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_c9b217-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_c9b217-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_c9b217-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_c9b217-11 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col,.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_5b4c15-a6{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_5b4c15-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_5b4c15-a6 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5, .wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5[data-kb-block=\"kb-adv-heading8834_233d73-d5\"]{font-size:22px;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5[data-kb-block=\"kb-adv-heading8834_233d73-d5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_233d73-d5[data-kb-block=\"kb-adv-heading8834_233d73-d5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_233d73-d5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_233d73-d5\">1. Reinigung <em>\u2013 PureMelt Radiance Balm<\/em><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07, .wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07[data-kb-block=\"kb-adv-heading8834_15bb86-07\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07[data-kb-block=\"kb-adv-heading8834_15bb86-07\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_15bb86-07[data-kb-block=\"kb-adv-heading8834_15bb86-07\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_15bb86-07 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_15bb86-07\">Nur gereinigte Haut kann Wirkstoffe optimal aufnehmen.<br>Der <em>PureMelt Radience Balm<\/em> kombiniert n\u00e4hrende, kaltgepresste \u00d6le mit sanften Emulgatoren. Beim Kontakt mit Wasser verwandelt er sich in eine milde <em>Emulsion<\/em>, die Make-up und Unreinheiten gr\u00fcndlich <em>entfernt <\/em>\u2013 ganz ohne Spannungsgef\u00fchl oder Fettfilm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihre Haut f\u00fchlt sich danach <em>weich<\/em>, <em>gepflegt <\/em>und <em>aufnahmebereit <\/em>an.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns8834_0c8034-b7{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:flex-end;}.kt-btns8834_0c8034-b7 .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns8834_0c8034-b7{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns8834_0c8034-b7{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8834_0c8034-b7\"><style>.wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button{width:200px;}.wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button{font-weight:400;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button{width:200px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_e9d680-80.kb-button{width:320px;}}<\/style><a class=\"kb-button kt-button button kb-btn8834_e9d680-80 kt-btn-size-small kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/de\/produkt\/pure-melt-radiance-balm\/\"><span class=\"kt-btn-inner-text\"><strong>JETZT KAUFEN<\/strong><\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8834_a3f91c-59{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_a3f91c-59 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_a3f91c-59{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:60px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8834_a3f91c-59 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}.kb-row-layout-id8834_a3f91c-59{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_a3f91c-59 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_fefc77-61 > .kt-inside-inner-col{display:flex;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column8834_fefc77-61 > .kt-inside-inner-col,.kadence-column8834_fefc77-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_fefc77-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_fefc77-61{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_fefc77-61{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_fefc77-61 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_fefc77-61{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_fefc77-61{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_fefc77-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_fefc77-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_fefc77-61 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6, .wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6[data-kb-block=\"kb-adv-heading8834_ecbe45-f6\"]{font-size:22px;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6[data-kb-block=\"kb-adv-heading8834_ecbe45-f6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_ecbe45-f6[data-kb-block=\"kb-adv-heading8834_ecbe45-f6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_ecbe45-f6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_ecbe45-f6\">2. Essence \u2013 das Herzst\u00fcck der Linie \u2013 <em>Floral Renewal Essence<\/em><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3, .wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3[data-kb-block=\"kb-adv-heading8834_f6374d-d3\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3[data-kb-block=\"kb-adv-heading8834_f6374d-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_f6374d-d3[data-kb-block=\"kb-adv-heading8834_f6374d-d3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_f6374d-d3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_f6374d-d3\">Diese Essence ist das konzentrierte <em>Herz <\/em>von Lantestina \u2013 ein harmonisches Zusammenspiel aus <em>Rosenhydrolat<\/em>, sieben sorgf\u00e4ltig ausgew\u00e4hlten <em>Pflanzenextrakten<\/em>, <em>pr\u00e4biotischen <\/em>Inhaltsstoffen und dem heilenden Gro\u00dfen <em>Wiesenknopf<\/em>. Sie wirkt <em>beruhigend<\/em>, <em>feuchtigkeitsspendend<\/em>, <em>regenerierend <\/em>und schenkt einen nat\u00fcrlichen <em>Glow<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Floral Renewal Essence<\/em> ist <em>Natur<\/em>, <em>Wissenschaft <\/em>und <em>Zartheit <\/em>in einem Flakon.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns8834_3ac89e-cb{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:flex-end;}.kt-btns8834_3ac89e-cb .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns8834_3ac89e-cb{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns8834_3ac89e-cb{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8834_3ac89e-cb\"><style>.wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button{width:200px;}.wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button{font-weight:400;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button{width:200px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_916878-4d.kb-button{width:320px;}}<\/style><a class=\"kb-button kt-button button kb-btn8834_916878-4d kt-btn-size-small kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/de\/produkt\/floral-renewal-essence\/\"><span class=\"kt-btn-inner-text\"><strong>JETZT KAUFEN<\/strong><\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{display:flex;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col,.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_c8fefe-b9{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_c8fefe-b9{position:relative;}.kadence-column8834_c8fefe-b9, .kt-inside-inner-col > .kadence-column8834_c8fefe-b9:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_c8fefe-b9{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_c8fefe-b9{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c8fefe-b9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_c8fefe-b9 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap{max-width:1920px;overflow:hidden;}.kt-img-overlay8834_a5049c-05{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:66.6667%;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap, .kt-img-overlay8834_a5049c-05 .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a5049c-05 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a5049c-05 .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap{max-width:1920px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_a5049c-05 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_a5049c-05 .kt-image-overlay-wrap{max-width:1920px;}.kt-img-overlay8834_a5049c-05 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_a5049c-05 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija.jpg\" alt=\"\" width=\"1920\" height=\"1280\" class=\"kt-img-overlay wp-image-8999\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija.jpg 1920w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-300x200.jpg 300w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-1024x683.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-768x512.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-1536x1024.jpg 1536w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-380x253.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Esencija-700x467.jpg 700w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_fd9a5c-29 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_fd9a5c-29 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_fd9a5c-29 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8834_fd9a5c-29{border-bottom:1px solid var(--global-palette3, #1A202C);}.kb-row-layout-id8834_fd9a5c-29 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_fd9a5c-29 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id8834_fd9a5c-29{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.kb-row-layout-id8834_fd9a5c-29 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:80px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:80px;padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_fd9a5c-29{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_fd9a5c-29 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_010763-95 > .kt-inside-inner-col{display:flex;}.kadence-column8834_010763-95 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_010763-95 > .kt-inside-inner-col,.kadence-column8834_010763-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_010763-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_010763-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_010763-95{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_010763-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_010763-95{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_010763-95{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_010763-95{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_010763-95 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_010763-95 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap{max-width:1707px;overflow:hidden;}.kt-img-overlay8834_86a824-b8{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap, .kt-img-overlay8834_86a824-b8 .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_86a824-b8 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_86a824-b8 .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap{max-width:1707px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_86a824-b8 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap{max-width:1707px;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:150%;}.kt-img-overlay8834_86a824-b8 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_86a824-b8 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" class=\"kt-img-overlay wp-image-9002\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-scaled.jpg 1707w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-200x300.jpg 200w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-683x1024.jpg 683w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-768x1152.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-1024x1536.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-1365x2048.jpg 1365w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-380x570.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Krema-700x1050.jpg 700w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8834_b3d457-66 > .kt-inside-inner-col{display:flex;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col,.kadence-column8834_b3d457-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_b3d457-66{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_b3d457-66{position:relative;}.kadence-column8834_b3d457-66, .kt-inside-inner-col > .kadence-column8834_b3d457-66:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_b3d457-66{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_b3d457-66{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_b3d457-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_b3d457-66 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_7a6f97-e1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_7a6f97-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_7a6f97-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:611px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_7a6f97-e1{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_7a6f97-e1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_7a6f97-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_7a6f97-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_7a6f97-e1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_f286be-6e > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_f286be-6e > .kt-inside-inner-col,.kadence-column8834_f286be-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_f286be-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_f286be-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_f286be-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_f286be-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_f286be-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_f286be-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_f286be-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_f286be-6e inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a, .wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a[data-kb-block=\"kb-adv-heading8834_5d9869-8a\"]{font-size:22px;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a[data-kb-block=\"kb-adv-heading8834_5d9869-8a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_5d9869-8a[data-kb-block=\"kb-adv-heading8834_5d9869-8a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_5d9869-8a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_5d9869-8a\">3. Feuchtigkeit &amp; Pflege \u2013 <em>Complexion Bliss Cream<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf die Essence folgt unsere <em>Complexion Bliss Cream<\/em> \u2013 sie versorgt die Haut mit <em>Feuchtigkeit <\/em>und wertvollen <em>Lipiden<\/em>. <em>Pflanzliche Hyalurons\u00e4ure <\/em>verbindet sich mit \u00d6len aus Aprikosenkernen, Mohn, Himbeeren und Haseln\u00fcssen zu einer seidigen Textur, die tiefenwirksam <em>n\u00e4hrt<\/em>, ohne zu beschweren.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns8834_482fac-bd{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:flex-end;}.kt-btns8834_482fac-bd .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns8834_482fac-bd{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns8834_482fac-bd{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8834_482fac-bd\"><style>.wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button{width:200px;}.wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button{font-weight:400;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button{width:200px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_ee922a-01.kb-button{width:320px;}}<\/style><a class=\"kb-button kt-button button kb-btn8834_ee922a-01 kt-btn-size-small kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/de\/produkt\/complexion-bliss-cream\/\"><span class=\"kt-btn-inner-text\"><strong>JETZT KAUFEN<\/strong><\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1440px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8834_e68487-1e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:80px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8834_e68487-1e > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_e68487-1e alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{display:flex;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{padding-right:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col,.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_2f1ee6-c8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_2f1ee6-c8{position:relative;}.kadence-column8834_2f1ee6-c8, .kt-inside-inner-col > .kadence-column8834_2f1ee6-c8:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{padding-left:0px;flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_2f1ee6-c8{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_2f1ee6-c8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_2f1ee6-c8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_2f1ee6-c8 inner-column-1\" data-aos=\"zoom-in\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8834_e630da-95 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8834_e630da-95 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8834_e630da-95 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:580px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8834_e630da-95{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-row-layout-id8834_e630da-95 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8834_e630da-95 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8834_e630da-95 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8834_e630da-95 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8834_4b00db-64 > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_4b00db-64 > .kt-inside-inner-col,.kadence-column8834_4b00db-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_4b00db-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_4b00db-64 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8834_4b00db-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8834_4b00db-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_4b00db-64{position:relative;}@media all and (max-width: 1024px){.kadence-column8834_4b00db-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8834_4b00db-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_4b00db-64 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99, .wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99[data-kb-block=\"kb-adv-heading8834_daf1a0-99\"]{font-size:22px;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99[data-kb-block=\"kb-adv-heading8834_daf1a0-99\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_daf1a0-99[data-kb-block=\"kb-adv-heading8834_daf1a0-99\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_daf1a0-99 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_daf1a0-99\">4. Schutz &amp; Abschluss \u2013 <em>FlutterSoft Elixir<\/em><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63, .wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63[data-kb-block=\"kb-adv-heading8834_e5b149-63\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63[data-kb-block=\"kb-adv-heading8834_e5b149-63\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8834_e5b149-63[data-kb-block=\"kb-adv-heading8834_e5b149-63\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8834_e5b149-63 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8834_e5b149-63\">Als letzter Schritt der Routine schlie\u00dft dieses <em>Elixier <\/em>die Pflege ab.<br>Das <em>\u00d6lserum <\/em>mit leichten, schnell einziehenden Pflanzen\u00f6len bildet einen <em>sch\u00fctzenden <\/em>Film, der die <em>Hautbarriere <\/em>st\u00e4rkt, <em>Feuchtigkeit <\/em>bewahrt und die Wirksamkeit der vorherigen Produkte erh\u00e4lt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lantestina ist eine Einladung, zur wahren Essenz der Hautpflege zur\u00fcckzukehren \u2013 pur, naturinspiriert und geschaffen f\u00fcr Haut, die <em>atmen<\/em>, <em>strahlen<\/em> und in ihrem nat\u00fcrlichen <em>Gleichgewicht <\/em>bleiben soll.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns8834_6690a6-57{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:flex-end;}.kt-btns8834_6690a6-57 .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns8834_6690a6-57{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns8834_6690a6-57{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8834_6690a6-57\"><style>.wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button{width:200px;}.wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button{font-weight:400;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button{width:200px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn8834_073b22-4f.kb-button{width:320px;}}<\/style><a class=\"kb-button kt-button button kb-btn8834_073b22-4f kt-btn-size-small kt-btn-width-type-fixed kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/de\/produkt\/flutter-soft-elixir\/\"><span class=\"kt-btn-inner-text\">JETZT KAUFEN<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column8834_c29579-7c > .kt-inside-inner-col{display:flex;}.kadence-column8834_c29579-7c > .kt-inside-inner-col{padding-right:0px;padding-left:0px;}.kadence-column8834_c29579-7c > .kt-inside-inner-col,.kadence-column8834_c29579-7c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8834_c29579-7c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c29579-7c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8834_c29579-7c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8834_c29579-7c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8834_c29579-7c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8834_c29579-7c{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8834_c29579-7c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column8834_c29579-7c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8834_c29579-7c inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap{max-width:1707px;overflow:hidden;}.kt-img-overlay8834_a9c0da-26{padding-right:0px;padding-bottom:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap:has(:focus-visible) .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap:hover .kt-image-overlay-color-wrapper{opacity:0 !important;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-color{background-color:var(--global-palette9, #ffffff);opacity:1;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap, .kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);inset:0px;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message .image-overlay-title{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-divider{border-top-color:#fff;border-top-width:1px;width:80%;border-top-style:none;}.wp-block-kadence-imageoverlay.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message .image-overlay-subtitle{color:#fff;background:rgba(0, 0, 0, 0);padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-weight:regular;font-style:normal;}@media all and (max-width: 1024px){.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap{max-width:1707px;}}@media all and (max-width: 1024px){.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:100%;}}@media all and (max-width: 1024px){.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap{max-width:1707px;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-wrap .kt-block-intrisic{padding-bottom:150%;}.kt-img-overlay8834_a9c0da-26 .kt-image-overlay-message{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:0px solid var(--global-palette6, #718096);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<div class=\"kt-img-overlay8834_a9c0da-26 aligncenter wp-block-kadence-imageoverlay\"><div class=\"kt-image-overlay-wrap kt-over-image-zoomin\"><div class=\"kt-block-intrisic kt-over-set-ratio\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" class=\"kt-img-overlay wp-image-9005\" srcset=\"https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-scaled.jpg 1707w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-200x300.jpg 200w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-683x1024.jpg 683w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-768x1152.jpg 768w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-1024x1536.jpg 1024w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-1365x2048.jpg 1365w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-380x570.jpg 380w, https:\/\/www.lantestina.com\/wp-content\/uploads\/Serum-700x1050.jpg 700w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><div class=\"kt-image-overlay-color-wrapper\"><div class=\"kt-image-overlay-color\"><\/div><\/div><span class=\"kt-imageoverlay-link\"><div class=\"kt-image-overlay-message kt-over-substyle-visible kt-over-valign-center kt-over-halign-center\"><div class=\"kt-image-overlay-inner\"><\/div><\/div><\/span><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Wieso Lantestina? Naturkosmetik inspiriert von blumen Lantestina ist eine zertifizierte Linie f\u00fcr nat\u00fcrliche &amp; biologische Kosmetik, entstanden aus der \u00dcberzeugung, dass die wertvollsten Wirkstoffe aus den Pflanzen kommen, die uns umgeben. Wir glauben an die Kraft des Lokalen und Wirkstoffreichen \u2013 und entwickeln Hautpflegeprodukte, die genau das beweisen. Was uns besonders macht Wiesenkr\u00e4uter \u2013 ein&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","iawp_total_views":28,"footnotes":""},"class_list":["post-8834","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Viktoria","author_link":"https:\/\/www.lantestina.com\/de\/author\/viktoria\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/pages\/8834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/comments?post=8834"}],"version-history":[{"count":8,"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/pages\/8834\/revisions"}],"predecessor-version":[{"id":10765,"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/pages\/8834\/revisions\/10765"}],"wp:attachment":[{"href":"https:\/\/www.lantestina.com\/de\/wp-json\/wp\/v2\/media?parent=8834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}